{"id":1207,"date":"2024-05-16T15:47:40","date_gmt":"2024-05-16T15:47:40","guid":{"rendered":"https:\/\/qrealo.cl\/newportschool\/index.php\/2024\/05\/16\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/"},"modified":"2024-05-16T15:47:40","modified_gmt":"2024-05-16T15:47:40","slug":"criterios-para-elegir-el-mejor-colegio-para-tus-hijos","status":"publish","type":"blog","link":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/","title":{"rendered":"Criterios para elegir el mejor colegio para tus hijos"},"content":{"rendered":"<div class=\"row-fluid-wrapper row-depth-1 row-number-6 \">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-cell \" data-widget-type=\"cell\" data-x=\"0\" data-w=\"12\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-7 \">\n<div class=\"row-fluid \">\n<div class=\"span1 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"1\">\n<div id=\"hs_cos_wrapper_module_1594334446948378\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-space\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n       <span class=\"hs-horizontal-spacer\"><\/span>\n      <\/div>\n<\/p><\/div>\n<p>     <!--end widget-span --> <\/p>\n<div class=\"span10 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"1\" data-w=\"10\">\n<div id=\"hs_cos_wrapper_module_1594157333248284\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-blog_content\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<div class=\"blog-section blog_col_in\">\n<div class=\"blog-post-wrapper cell-wrapper A\">\n<div class=\"section post-header clearfix\">\n<div class=\"topic_name_post_in\">\n           <span class=\"img_topic__\"><\/span><br \/>\n           <span class=\"topic_text\"> Aprendizaje <\/span>\n          <\/div>\n<h1> <span id=\"hs_cos_wrapper_name\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"text\">Criterios para elegir el mejor colegio para tus hijos<\/span> <\/h1>\n<\/p><\/div>\n<div class=\"section post-body\">\n          <span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\"><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041.jpg\" alt=\"_MG_4041\" width=\"600\" style=\"width: 600px;margin: 0px auto\"><\/p>\n<p style=\"text-align: justify;font-size: 18px\">Llegamos a la recta final del a\u00f1o, momento en el que muchos padres de familia empiezan a considerar ingresar a sus hijos por primera vez al colegio o que analizan la posibilidad de buscar una nueva opci\u00f3n educativa. Sabemos que esta decisi\u00f3n <strong>no es tarea f\u00e1cil<\/strong> y que a veces puede ser complejo reconocer si realmente una instituci\u00f3n en particular es la que ofrece las mejores alternativas. Por eso te dejamos una lista con los <strong>cuatro criterios<\/strong> que deber\u00edas revisar con lupa al momento de evaluar un colegio para tus ni\u00f1os.<\/p>\n<p>           <!--more--> <\/p>\n<p style=\"text-align: justify\">\n<p><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-01-3.png\" alt=\"Colegio-01\" width=\"471\" style=\"width: 471px;margin: 0px auto\"><br \/><span style=\"font-size: 18px\">Los <strong>m\u00e9todos de ense\u00f1anza<\/strong> son el criterio m\u00e1s importante a tener en cuenta, ya que estos definen la forma como aprenden los ni\u00f1os, as\u00ed como la eficacia con la que retienen dichos conocimientos y los aplican al mundo real. Es crucial tener presente que la metodolog\u00eda debe incluir no solamente las materias b\u00e1sicas, sino tambi\u00e9n <strong>estrategias diferenciales para cada nivel escolar y de adaptaci\u00f3n a las necesidades de cada etapa.<\/strong> De igual manera, es ideal que emplee la utilizaci\u00f3n de <strong>herramientas tecnol\u00f3gicas<\/strong> \u00fatiles y flexibles para el proceso de aprendizaje.<br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\">Al momento de revisar la metodolog\u00eda aseg\u00farate de que esta incluya:<br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-05-Feb-28-2024-05-12-43-5098-PM.png\" alt=\"Colegio-05\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><br \/>M\u00e9todos que fomenten el <strong>gusto por aprender<\/strong> y desarrollen en los ni\u00f1os factores <\/span><span style=\"font-size: 18px\">como la responsabilidad, la creatividad y la autonom\u00eda.<br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><br \/><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-06-Feb-28-2024-05-12-26-9467-PM.png\" alt=\"Colegio-06\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><br \/>Espacios que estimulen la realizaci\u00f3n de <strong>actividades art\u00edsticas y deportivas<\/strong> como complemento de su proceso educativo.<br \/><\/span><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-07-1.png\" alt=\"Colegio-07\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><br \/>Herramientas tecnol\u00f3gicas que ampl\u00eden el espectro del ambiente educativo a <strong>escenarios virtuales y remotos.<\/strong><br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong>&nbsp;<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\">En<strong> Newport School<\/strong> nos aseguramos de cumplir con estos criterios, por eso nuestra metodolog\u00eda incluye:<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-08-4.png\" alt=\"Colegio-08\" width=\"150\" style=\"width: 150px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\">Project Based Learning (PBL): <\/strong>conocido en espa\u00f1ol como Aprendizaje Basado en Proyectos, es un m\u00e9todo de ense\u00f1anza que combina dominio del contenido, trabajo significativo y conexi\u00f3n personal para crear <span style=\"font-weight: bold\">experiencias de aprendizaje poderosas.<\/span> Con esta metodolog\u00eda, los ni\u00f1os adquieren competencias claves para desenvolverse en su entorno al planificar, estructurar y elaborar un proyecto propio que resuelva una problem\u00e1tica real.&nbsp; Conoce m\u00e1s de esta metodolog\u00eda <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/metodologia-de-aprendizaje\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed.<\/strong><\/span><\/a><\/span><br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-09.png\" alt=\"Colegio-09\" width=\"150\" style=\"width: 150px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><br \/>e-Learning:<\/strong> creemos que el uso de la tecnolog\u00eda facilita el proceso de ense\u00f1anza, por eso implementamos <span style=\"font-weight: bold\">Moodle,<\/span> la plataforma virtual de aprendizaje m\u00e1s utilizada en el mundo, que nos permite flexibilizar el trabajo colaborativo, la gesti\u00f3n de actividades y la comunicaci\u00f3n con nuestras familias. Conoce m\u00e1s de nuestro m\u00e9todo e-Learning <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/elearning\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed.<\/strong><\/span><\/a><\/span><\/span><\/p>\n<p style=\"text-align: justify\">\n<p><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-02-3.png\" alt=\"Colegio-02\" width=\"471\" style=\"width: 471px;margin: 0px auto\"><br \/><span style=\"font-size: 18px\">La <strong>ense\u00f1anza de un segundo idioma<\/strong> trae m\u00faltiples ventajas en el desarrollo de los estudiantes, y estas se intensifican cuando se realiza desde edades tempranas. Hablar un idioma diferente al propio ayuda a que los ni\u00f1os tengan una <strong>mejor capacidad de atenci\u00f3n<\/strong> y a que aprendan a <strong>realizar m\u00faltiples tareas mejor<\/strong> que los monoling\u00fces. Adem\u00e1s, al incluir un aprendizaje multicultural, los ni\u00f1os no solo adquieren habilidades ling\u00fc\u00edsticas, sino que tambi\u00e9n aprenden a <strong>ser m\u00e1s emp\u00e1ticos y tolerantes,<\/strong> habilidades sociales necesarias para interactuar con personas de diferentes or\u00edgenes.<\/span><\/p>\n<p style=\"text-align: justify;font-size: 18px\">El aprendizaje de un segundo idioma es un <strong>aspecto vital en Newport School,<\/strong> el cual va de la mano con el aspecto cultural. Por eso nuestra forma de aprender otro idioma tiene tres enfoques:<br \/><span style=\"font-size: 18px\"><br \/><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-10-Feb-28-2024-05-12-46-1885-PM.png\" alt=\"Colegio-10\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><br \/><\/span><strong>Directo:<\/strong> nuestras clases inician con un di\u00e1logo en estilo de conversaci\u00f3n casual en el segundo idioma. La lengua materna no se usa y no hay traducci\u00f3n.<\/p>\n<p style=\"text-align: justify;font-size: 18px\"><strong><span style=\"font-size: 18px\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-11-2.png\" alt=\"Colegio-11\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><\/span><\/strong><strong><br \/>De lectura: <\/strong>ense\u00f1amos la gram\u00e1tica necesaria para la comprensi\u00f3n y fluidez de la lectura. Realizamos un enfoque importante en el vocabulario.<\/p>\n<p style=\"text-align: justify;font-size: 18px\"><strong><span style=\"font-size: 18px\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-12-1.png\" alt=\"Colegio-12\" width=\"100\" style=\"width: 100px;float: left;margin-right: 10px;margin-bottom: 0px;margin-left: 20px\"><\/span><br \/>Audioling\u00fcista: <\/strong>la comprensi\u00f3n auditiva, la expresi\u00f3n oral, la lectura y la escritura se desarrollan en orden. Usamos ayudas visuales y de audio. Se da gran importancia a la pronunciaci\u00f3n precisa como nativa.<strong><br \/><\/strong><\/p>\n<p style=\"text-align: justify;font-size: 18px\">Conoce m\u00e1s de nuestro enfoque biling\u00fce <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/bilinguismo\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed. <\/strong><\/span><\/a><br \/><\/span><\/p>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-03-1.png\" alt=\"Colegio-03\" width=\"471\" style=\"width: 471px;margin: 0px auto\"><\/p>\n<p style=\"text-align: justify;font-size: 18px\">A nivel mundial existen diferentes organizaciones l\u00edderes en educaci\u00f3n que miden a las instituciones educativas de todos los niveles y reconocen sus buenas pr\u00e1cticas en distintos aspectos. Que un colegio cuente con certificaciones de este tipo <strong>valida la calidad del proceso escolar que ofrece,<\/strong> al estar respaldado por <strong>criterios internacionales,<\/strong> y permite adem\u00e1s que los estudiantes sean parte de intercambios de conocimiento multiculturales y multifac\u00e9ticos.<\/p>\n<p style=\"text-align: justify;font-size: 18px\">Actualmente, <strong>Newport School cuenta con varias certificaciones internacionales:<\/p>\n<p><\/strong><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Landing-10-1.png\" alt=\"Landing-10\" width=\"100\" style=\"width: 100px;float: left;margin: 0px 10px 10px 20px\"><strong>Great Place to Study: <\/strong>esta certificaci\u00f3n proveniente de la India, mide la <strong>felicidad como un factor tangible para las comunidades educativas.<\/strong> Ser Great Place to Study significa que nos preocupamos por el <strong>bienestar emocional de nuestros estudiantes,<\/strong> y que su experiencia de aprendizaje se desarrolla en un ambiente feliz y c\u00f3modo.<\/p>\n<p><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Landing-12-1.png\" alt=\"Landing-12\" width=\"100\" style=\"width: 100px;float: left;margin: 0px 10px 10px 20px\">Eco &#8211; Schools: <\/strong>este es un programa de Dinamarca que reconoce a las instituciones que fomentan en sus estudiantes el <strong>cuidado del entorno de manera consciente<\/strong> para que logren un impacto positivo en su comunidad.<\/span><\/p>\n<p style=\"text-align: justify\">&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Landing-11-2.png\" alt=\"Landing-11\" width=\"100\" style=\"width: 100px;float: left;margin: 0px 10px 10px 20px\">Cognia AvancED: <\/strong>esta es una organizaci\u00f3n de Estados Unidos conocida por ser la <strong>comunidad de docentes m\u00e1s grande del mundo.<\/strong> En este momento nos encontramos en procesos para obtener su certificaci\u00f3n la cual mide nuestro m\u00e9todo educativo como un modelo innovador de aprendizaje.<\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\">Conoce m\u00e1s sobre nuestras certificaciones y reconocimientos <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/reconocimientos-y-certificaciones\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed.<\/strong><\/span><\/a><\/p>\n<p><\/span><\/span><\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-04.png\" alt=\"Colegio-04\" width=\"471\" style=\"width: 471px;margin: 0px auto\"><\/p>\n<p style=\"font-size: 18px;text-align: justify\">Los cambios y retos que nos trajo este 2020 como consecuencia del COVID-19 han hecho que <strong>la seguridad a nivel sanitario sea una de las nuevas prioridades para las instituciones y padres de familia,<\/strong> todo esto con el prop\u00f3sito de no frenar el proceso educativo de los ni\u00f1os. Es por esto que la implementaci\u00f3n de un modelo de bioseguridad de cara al regreso seguro y paulatino a las aulas de clase, es otro de los factores a tener en cuenta al momento de elegir un colegio para tus hijos.&nbsp;<\/p>\n<p style=\"font-size: 18px;text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Landing-13-3.png\" alt=\"Landing-13\" width=\"120\" style=\"width: 120px;float: left;margin: 0px 10px 10px 20px\"><\/strong><\/span>En <strong>Newport School<\/strong> nos hemos venido preparando durante este tiempo de aislamiento para adecuar nuestros espacios de la mejor manera. Es as\u00ed como obtuvimos el sello <strong>\u2018Safe Guard\u2019<\/strong> por parte de <strong>Bureau Veritas Colombia.<\/strong> Este sello certifica que cumplimos con todas las medidas de bioseguridad exigidas por las autoridades para garantizar la seguridad que necesitan las familias.<\/p>\n<p style=\"font-size: 18px;text-align: justify\">Te invitamos a que eches un vistazo a nuestro proceso de preparaci\u00f3n para volver a abrir nuestras puertas:<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-13-Feb-28-2024-05-12-48-5927-PM.png\" alt=\"Colegio-13\" width=\"80\" style=\"width: 80px;float: left;margin: 0px 10px 10px 20px\"><\/strong><br \/>Conoce <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/estrategiacovid19\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed<\/strong>&nbsp;<\/span><\/a><\/span>nuestra estrategia de adaptaci\u00f3n a la nueva realidad.<br \/><\/span><span style=\"font-size: 18px\"><br \/><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 18px\"><strong><img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/Colegio-13-Feb-28-2024-05-12-48-5927-PM.png\" alt=\"Colegio-13\" width=\"80\" style=\"width: 80px;float: left;margin: 0px 10px 10px 20px\"><\/strong><br \/>Conoce <span style=\"color: #000000\"><a href=\"https:\/\/www.newportschool.edu.co\/es\/alternanciaacademica\" rel=\"noopener\" target=\"_blank\" style=\"color: #000000\"><span style=\"text-decoration: underline\"><strong>aqu\u00ed<\/strong>&nbsp;<\/span><\/a><\/span>nuestro modelo de alternancia acad\u00e9mica que implementaremos en 2021.<\/p>\n<p><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><\/span>\n         <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>     <!--end widget-span --> <\/p>\n<div class=\"span1 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"11\" data-w=\"1\">\n<div id=\"hs_cos_wrapper_module_1594334451948379\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-space\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n       <span class=\"hs-horizontal-spacer\"><\/span>\n      <\/div>\n<\/p><\/div>\n<p>     <!--end widget-span -->\n    <\/div>\n<p>    <!--end row-->\n   <\/div>\n<p>   <!--end row-wrapper -->\n  <\/div>\n<p>  <!--end widget-span -->\n <\/div>\n<p> <!--end row-->\n<\/div>\n<p><!--end row-wrapper --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te dejamos una lista con los cuatro criterios que deber\u00edas revisar con lupa al momento de evaluar un colegio para tus ni\u00f1os.<\/p>\n","protected":false},"featured_media":1317,"template":"","class_list":["post-1207","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Te dejamos una lista con los cuatro criterios que deber\u00edas revisar con lupa al momento de evaluar un colegio para tus ni\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/\" \/>\n<meta property=\"og:site_name\" content=\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/newportschool\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/\",\"name\":\"Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg\",\"datePublished\":\"2024-05-16T15:47:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Criterios para elegir el mejor colegio para tus hijos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"description\":\"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!\",\"publisher\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"width\":808,\"height\":388,\"caption\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/newportschool\\\/\",\"https:\\\/\\\/instagram.com\\\/newportschool\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkuOH6cSzNNej7FE8wZ4bMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/","og_locale":"es_ES","og_type":"article","og_title":"Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","og_description":"Te dejamos una lista con los cuatro criterios que deber\u00edas revisar con lupa al momento de evaluar un colegio para tus ni\u00f1os.","og_url":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/","og_site_name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/newportschool\/","og_image":[{"url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/","url":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/","name":"Criterios para elegir el mejor colegio para tus hijos - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","isPartOf":{"@id":"https:\/\/newportschool.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/#primaryimage"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/#primaryimage"},"thumbnailUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg","datePublished":"2024-05-16T15:47:40+00:00","breadcrumb":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/#primaryimage","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/MG_4041-Feb-28-2024-05-02-18-3611-PM-scaled-1.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/newportschool.edu.co\/es\/blog\/criterios-para-elegir-el-mejor-colegio-para-tus-hijos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newportschool.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"Criterios para elegir el mejor colegio para tus hijos"}]},{"@type":"WebSite","@id":"https:\/\/newportschool.edu.co\/es\/#website","url":"https:\/\/newportschool.edu.co\/es\/","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!","publisher":{"@id":"https:\/\/newportschool.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newportschool.edu.co\/es\/#organization","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","url":"https:\/\/newportschool.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","width":808,"height":388,"caption":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/newportschool\/","https:\/\/instagram.com\/newportschool\/","https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog\/1207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media\/1317"}],"wp:attachment":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media?parent=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}