{"id":246,"date":"2024-05-16T15:53:03","date_gmt":"2024-05-16T15:53:03","guid":{"rendered":"https:\/\/qrealo.cl\/newportschool\/index.php\/2024\/05\/16\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/"},"modified":"2024-05-16T15:53:03","modified_gmt":"2024-05-16T15:53:03","slug":"cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib","status":"publish","type":"blog","link":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/","title":{"rendered":"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB?"},"content":{"rendered":"<div class=\"row-fluid-wrapper row-depth-1 row-number-6 \">\n<div class=\"row-fluid \">\n<div class=\"span12 widget-span widget-type-cell \" data-widget-type=\"cell\" data-x=\"0\" data-w=\"12\">\n<div class=\"row-fluid-wrapper row-depth-1 row-number-7 \">\n<div class=\"row-fluid \">\n<div class=\"span1 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"0\" data-w=\"1\">\n<div id=\"hs_cos_wrapper_module_1594334446948378\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-space\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n       <span class=\"hs-horizontal-spacer\"><\/span>\n      <\/div>\n<\/p><\/div>\n<p>     <!--end widget-span --> <\/p>\n<div class=\"span10 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"1\" data-w=\"10\">\n<div id=\"hs_cos_wrapper_module_1594157333248284\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-blog_content\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n<div class=\"blog-section blog_col_in\">\n<div class=\"blog-post-wrapper cell-wrapper A\">\n<div class=\"section post-header clearfix\">\n<div class=\"topic_name_post_in\">\n           <span class=\"img_topic__\"><\/span><br \/>\n           <span class=\"topic_text\"> Aprendizaje <\/span>\n          <\/div>\n<h1> <span id=\"hs_cos_wrapper_name\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"text\">\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB?<\/span> <\/h1>\n<\/p><\/div>\n<div class=\"section post-body\">\n          <span id=\"hs_cos_wrapper_post_body\" class=\"hs_cos_wrapper hs_cos_wrapper_meta_field hs_cos_wrapper_type_rich_text\" data-hs-cos-general-type=\"meta_field\" data-hs-cos-type=\"rich_text\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-14-0384-PM.png\" alt=\"perfil IB-1\" width=\"554\" height=\"369\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 554px;margin-left: auto;margin-right: auto\"><\/p>\n<p style=\"font-size: 16px;text-align: justify\">El <strong>Bachillerato Internacional<\/strong> tiene como meta formar j\u00f3venes solidarios, informados y \u00e1vidos de conocimiento, con habilidades de construcci\u00f3n para crear un mundo mejor y m\u00e1s tranquilo, dentro del marco del entendimiento mutuo y el respeto intercultural.<\/p>\n<p>           <!--more--> <\/p>\n<p style=\"font-size: 16px;text-align: justify\">De la misma forma, los programas del IB no se enfocan \u00fanicamente en el desarrollo cognitivo, sino que tambi\u00e9n se tiene en cuenta el <strong>bienestar social, emocional y f\u00edsico<\/strong> de los alumnos, as\u00ed como tambi\u00e9n de asegurar que ellos aprendan a respetarse a s\u00ed mismos, y a los dem\u00e1s.<\/p>\n<p style=\"font-size: 16px;text-align: justify\">Los educadores del IB ayudan a los estudiantes a desarrollar y potencializar atributos durante su trayectoria por la educaci\u00f3n del IB. A trav\u00e9s de estos atributos, se logran sentar las bases para conseguir que la formaci\u00f3n de los alumnos crezca y fluya con una mentalidad internacional.<\/p>\n<p style=\"font-size: 16px;text-align: justify\">El perfil de la comunidad de aprendizaje ubica al estudiante en el <strong>centro<\/strong> de la formaci\u00f3n del IB, y cumple con sus diez atributos que reflejan la naturaleza de la educaci\u00f3n del Bachillerato Internacional, los cuales son:<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/inquirer-2.png\" alt=\"inquirer\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><\/strong><\/p>\n<p><span style=\"font-size: 16px\"><strong><br \/>Indagadores:<\/strong> Cultivan la capacidad y al mismo tiempo desarrollan habilidades para la indagaci\u00f3n y la investigaci\u00f3n.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/opneminded.png\" alt=\"opneminded\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\">De mentalidad abierta:<\/span><\/strong><span style=\"font-size: 16px\"> Desarrollan una apreciaci\u00f3n cr\u00edtica de las culturas propias e historias personales, as\u00ed como de los valores y tradiciones de los dem\u00e1s. Comprenden distintos puntos de vista y est\u00e1n dispuestos a aprender de la experiencia.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/knowledgeable-1.png\" alt=\"knowledgeable\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\"><br \/>Informados e instruidos:<\/span><\/strong><span style=\"font-size: 16px\"> Desarrollan y usan la comprensi\u00f3n conceptual mediante la exploraci\u00f3n del conocimiento en una variedad de disciplinas tanto en lo local como en lo internacional.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/caring-4.png\" alt=\"caring\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\"><br \/>Solidarios:<\/span><\/strong><span style=\"font-size: 16px\"> Muestran empat\u00eda, sensibilidad y respeto por los dem\u00e1s.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/thinker-Feb-28-2024-05-25-36-9751-PM.png\" alt=\"thinker\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\"><br \/>Pensadores:<\/span><\/strong><span style=\"font-size: 16px\"> Usan habilidades de pensamiento cr\u00edtico y creativo para lograr actuar de manera responsable ante problemas complejos.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/ricktaker-3.png\" alt=\"ricktaker\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\"><br \/>Audaces:<\/span><\/strong><span style=\"font-size: 16px\"> Trabajan de forma aut\u00f3noma y colaborativa para explorar nuevas ideas y estrategias innovadoras.<\/p>\n<p><\/span><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/communicator-Feb-28-2024-05-25-38-6504-PM.png\" alt=\"communicator\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><br \/><span style=\"font-size: 16px\">Buenos comunicadores:<\/span><\/strong><span style=\"font-size: 16px\"> Logran expresar con confianza y creatividad en diversas lenguas, lenguajes y maneras. De la misma forma, escuchan atentamente las perspectivas de otras personas.<\/span><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/balanced-1.png\" alt=\"balanced\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><br \/><span style=\"font-size: 16px\">Equilibrados:<\/span><\/strong><span style=\"font-size: 16px\"> Entienden la importancia del equilibrio f\u00edsico, mental y emocional para conseguir el bienestar propio y el de los dem\u00e1s.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p> <strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/principled.png\" alt=\"principled\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><br \/><span style=\"font-size: 16px\">\u00cdntegros:<\/span><\/strong><span style=\"font-size: 16px\"> Act\u00faan con integridad y honradez, con sentido de la equidad, la justicia y el respeto por la dignidad y los derechos de las personas.<\/span><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/refelctive-Feb-28-2024-05-25-34-3178-PM.png\" alt=\"refelctive\" width=\"94\" height=\"94\" loading=\"lazy\" style=\"height: auto;max-width: 100%;width: 94px;float: left\"><span style=\"font-size: 16px\"><br \/>Reflexivos:<\/span><\/strong><span style=\"font-size: 16px\"> Eval\u00faan el mundo y las ideas propias.<\/span> <\/p>\n<p>&nbsp;<\/p>\n<p><\/span>\n         <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<p>     <!--end widget-span --> <\/p>\n<div class=\"span1 widget-span widget-type-custom_widget \" data-widget-type=\"custom_widget\" data-x=\"11\" data-w=\"1\">\n<div id=\"hs_cos_wrapper_module_1594334451948379\" class=\"hs_cos_wrapper hs_cos_wrapper_widget hs_cos_wrapper_type_module widget-type-space\" data-hs-cos-general-type=\"widget\" data-hs-cos-type=\"module\">\n       <span class=\"hs-horizontal-spacer\"><\/span>\n      <\/div>\n<\/p><\/div>\n<p>     <!--end widget-span -->\n    <\/div>\n<p>    <!--end row-->\n   <\/div>\n<p>   <!--end row-wrapper -->\n  <\/div>\n<p>  <!--end widget-span -->\n <\/div>\n<p> <!--end row-->\n<\/div>\n<p><!--end row-wrapper --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Bachillerato Internacional tiene como meta formar j\u00f3venes solidarios, informados y \u00e1vidos de conocimiento, con habilidades de construcci\u00f3n para crear un mundo mejor y m\u00e1s tranquilo.<\/p>\n","protected":false},"featured_media":314,"template":"","class_list":["post-246","blog","type-blog","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"El Bachillerato Internacional tiene como meta formar j\u00f3venes solidarios, informados y \u00e1vidos de conocimiento, con habilidades de construcci\u00f3n para crear un mundo mejor y m\u00e1s tranquilo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/\" \/>\n<meta property=\"og:site_name\" content=\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/newportschool\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-14-0384-PM.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/\",\"name\":\"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png\",\"datePublished\":\"2024-05-16T15:53:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2025\\\/01\\\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/blog\\\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"description\":\"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!\",\"publisher\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"width\":808,\"height\":388,\"caption\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/newportschool\\\/\",\"https:\\\/\\\/instagram.com\\\/newportschool\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkuOH6cSzNNej7FE8wZ4bMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","og_description":"El Bachillerato Internacional tiene como meta formar j\u00f3venes solidarios, informados y \u00e1vidos de conocimiento, con habilidades de construcci\u00f3n para crear un mundo mejor y m\u00e1s tranquilo.","og_url":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/","og_site_name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/newportschool\/","og_image":[{"url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-14-0384-PM.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/","url":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/","name":"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB? - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","isPartOf":{"@id":"https:\/\/newportschool.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/#primaryimage"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/#primaryimage"},"thumbnailUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png","datePublished":"2024-05-16T15:53:03+00:00","breadcrumb":{"@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/#primaryimage","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2025\/01\/perfil-IB-1-Feb-28-2024-05-25-10-8988-PM.png","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/newportschool.edu.co\/es\/blog\/cual-es-el-perfil-de-la-comunidad-de-aprendizaje-ib\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newportschool.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1l es el perfil de la comunidad de aprendizaje IB?"}]},{"@type":"WebSite","@id":"https:\/\/newportschool.edu.co\/es\/#website","url":"https:\/\/newportschool.edu.co\/es\/","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!","publisher":{"@id":"https:\/\/newportschool.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newportschool.edu.co\/es\/#organization","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","url":"https:\/\/newportschool.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","width":808,"height":388,"caption":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/newportschool\/","https:\/\/instagram.com\/newportschool\/","https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog\/246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/types\/blog"}],"version-history":[{"count":0,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/blog\/246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media\/314"}],"wp:attachment":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media?parent=246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}