{"id":134466,"date":"2026-06-17T14:38:30","date_gmt":"2026-06-17T19:38:30","guid":{"rendered":"https:\/\/newportschool.edu.co\/?post_type=school-news&#038;p=134466"},"modified":"2026-06-17T14:38:30","modified_gmt":"2026-06-17T19:38:30","slug":"newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible","status":"publish","type":"school-news","link":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/","title":{"rendered":"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"134466\" class=\"elementor elementor-134466\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"school-news\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2a96a2 e-flex e-con-boxed e-con e-parent\" data-id=\"d2a96a2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e8fef5 elementor-widget elementor-widget-text-editor\" data-id=\"2e8fef5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"6\">En <b data-path-to-node=\"6\" data-index-in-node=\"3\">Newport School<\/b> la educaci\u00f3n del futuro se vive en nuestra infraestructura. Con gran orgullo compartimos con toda nuestra comunidad educativa una noticia hist\u00f3rica: <b data-path-to-node=\"6\" data-index-in-node=\"253\">hemos puesto en marcha nuestro propio sistema solar fotovoltaico<\/b>, un proyecto de vanguardia tecnol\u00f3gica que marca un antes y un despu\u00e9s en nuestro compromiso con el cuidado del medio ambiente.<\/p><p data-path-to-node=\"7\">Este gran paso nos consolida como un <b data-path-to-node=\"7\" data-index-in-node=\"37\">colegio verde y referente de innovaci\u00f3n en el \u00c1rea Metropolitana de Bucaramanga<\/b>, demostrando con hechos que la sostenibilidad es el pilar de nuestra identidad.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26592e1 e-flex e-con-boxed e-con e-parent\" data-id=\"26592e1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dfa12aa elementor-widget elementor-widget-heading\" data-id=\"dfa12aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfC\u00f3mo funciona este sistema?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d1bc664 e-flex e-con-boxed e-con e-parent\" data-id=\"d1bc664\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37d0728 elementor-widget elementor-widget-text-editor\" data-id=\"37d0728\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"10\">Para entender el impacto de esta obra, es fundamental conocer la tecnolog\u00eda que ahora viste las cubiertas de nuestra instituci\u00f3n. El sistema est\u00e1 compuesto por <b data-path-to-node=\"10\" data-index-in-node=\"160\">244 m\u00f3dulos o paneles solares de \u00faltima generaci\u00f3n<\/b>, los cuales fueron instalados estrat\u00e9gicamente en dos zonas clave: la cubierta del restaurante y la de la porter\u00eda principal.<\/p><p data-path-to-node=\"11\">El funcionamiento del sistema se resume en tres pasos clave:<\/p><ol start=\"1\" data-path-to-node=\"12\"><li><p data-path-to-node=\"12,0,0\"><b data-path-to-node=\"12,0,0\" data-index-in-node=\"0\">Captaci\u00f3n:<\/b> Cada uno de los paneles absorbe la radiaci\u00f3n solar gracias a sus celdas fotovoltaicas.<\/p><\/li><li><p data-path-to-node=\"12,1,0\"><b data-path-to-node=\"12,1,0\" data-index-in-node=\"0\">Transformaci\u00f3n:<\/b> En lugar de acumular calor, los paneles procesan esa luz y la transforman de manera directa en electricidad limpia.<\/p><\/li><li><p data-path-to-node=\"12,2,0\"><b data-path-to-node=\"12,2,0\" data-index-in-node=\"0\">Distribuci\u00f3n:<\/b> Esta corriente el\u00e9ctrica renovable se inyecta directamente a la red del colegio para alimentar los salones, laboratorios, pantallas y los sistemas de aire acondicionado.<\/p><\/li><\/ol><p data-path-to-node=\"13\">Con una capacidad instalada de <b data-path-to-node=\"13\" data-index-in-node=\"31\">80 kW pico<\/b> (donde cada m\u00f3dulo genera 675 vatios), este sistema est\u00e1 dise\u00f1ado para <b data-path-to-node=\"13\" data-index-in-node=\"113\">suplir el 37% de la carga energ\u00e9tica total de nuestro campus<\/b>. \u00a1Casi la mitad de la electricidad que consume el colegio proviene ahora directamente del sol!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f941580 elementor-widget elementor-widget-image\" data-id=\"f941580\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News1.webp?w=1536\" title=\"Instalacion_Paneles_Solares_NPS_News1\" alt=\"Instalacion_Paneles_Solares_NPS_News1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8082f9c e-flex e-con-boxed e-con e-parent\" data-id=\"8082f9c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ff6684 elementor-widget elementor-widget-heading\" data-id=\"1ff6684\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1xima seguridad y calidad certificada bajo la norma RETIE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82ea9fb e-flex e-con-boxed e-con e-parent\" data-id=\"82ea9fb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13739f4 elementor-widget elementor-widget-text-editor\" data-id=\"13739f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-path-to-node=\"16\">Para la tranquilidad de todos los padres de familia y el personal de la instituci\u00f3n, este proyecto no solo destaca por su eficiencia, sino por sus rigurosos est\u00e1ndares de protecci\u00f3n. El sistema solar de Newport School cuenta con todas las normativas el\u00e9ctricas vigentes en Colombia, habiendo superado con \u00e9xito las pruebas de calidad y sostenibilidad exigidas por la <b data-path-to-node=\"16\" data-index-in-node=\"367\">certificaci\u00f3n RETIE (Reglamento T\u00e9cnico de Instalaciones El\u00e9ctricas)<\/b>.<\/p><p data-path-to-node=\"17\">Esto garantiza una operaci\u00f3n 100% segura, eficiente y confiable para el d\u00eda a d\u00eda de nuestros estudiantes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-328f535 e-flex e-con-boxed e-con e-parent\" data-id=\"328f535\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9bfce0 elementor-widget elementor-widget-heading\" data-id=\"c9bfce0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beneficios de la energ\u00eda solar para Newport School<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9bebcc e-flex e-con-boxed e-con e-parent\" data-id=\"c9bebcc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f958cbb elementor-widget elementor-widget-text-editor\" data-id=\"f958cbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1750\" data-end=\"1874\">La implementaci\u00f3n de este sistema representa m\u00faltiples beneficios para nuestra comunidad educativa y para el medio ambiente.<\/p><h3 data-section-id=\"129k12j\" data-start=\"1876\" data-end=\"1915\">1. Reducci\u00f3n de la huella ambiental<\/h3><p data-start=\"1917\" data-end=\"2083\">Al generar energ\u00eda limpia, disminuimos la dependencia de fuentes energ\u00e9ticas convencionales y contribuimos a la reducci\u00f3n de emisiones asociadas al consumo el\u00e9ctrico.<\/p><h3 data-section-id=\"17yglaq\" data-start=\"2085\" data-end=\"2123\">2. Uso responsable de los recursos<\/h3><p data-start=\"2125\" data-end=\"2259\">La energ\u00eda solar aprovecha un recurso natural abundante y renovable, promoviendo una gesti\u00f3n m\u00e1s eficiente y consciente de la energ\u00eda.<\/p><h3 data-section-id=\"13hezqm\" data-start=\"2261\" data-end=\"2294\">3. Formaci\u00f3n con impacto real<\/h3><p data-start=\"2296\" data-end=\"2516\">Nuestros estudiantes no solo aprenden sobre sostenibilidad en el aula, sino que ahora pueden ver c\u00f3mo estas soluciones se implementan en su entorno cotidiano, fortaleciendo el aprendizaje a trav\u00e9s de experiencias reales.<\/p><h3 data-section-id=\"14jghfo\" data-start=\"2518\" data-end=\"2563\">4. Innovaci\u00f3n al servicio de la educaci\u00f3n<\/h3><p data-start=\"2565\" data-end=\"2756\">La incorporaci\u00f3n de tecnolog\u00edas limpias posiciona a Newport School como una instituci\u00f3n que apuesta por la innovaci\u00f3n y la preparaci\u00f3n de las nuevas generaciones para los desaf\u00edos del futuro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f0941a8 e-flex e-con-boxed e-con e-parent\" data-id=\"f0941a8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f9e428 elementor-widget elementor-widget-heading\" data-id=\"2f9e428\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">M\u00e1s que energ\u00eda: un compromiso con el futuro<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8277a77 e-flex e-con-boxed e-con e-parent\" data-id=\"8277a77\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ea7505 elementor-widget elementor-widget-text-editor\" data-id=\"1ea7505\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"3267\" data-end=\"3511\">La instalaci\u00f3n de este sistema solar fotovoltaico representa mucho m\u00e1s que una mejora tecnol\u00f3gica. Es una muestra concreta de nuestro compromiso con el cuidado del planeta y con la formaci\u00f3n de estudiantes conscientes de su impacto en el mundo.<\/p><p data-start=\"3513\" data-end=\"3681\">Cada rayo de sol que se transforma en energ\u00eda es tambi\u00e9n una oportunidad para seguir construyendo una cultura de sostenibilidad, innovaci\u00f3n y responsabilidad ambiental.<\/p><p data-start=\"3683\" data-end=\"3773\">En Newport School seguimos avanzando hacia un futuro m\u00e1s limpio, inteligente y sostenible.<\/p><p data-start=\"3775\" data-end=\"3823\"><strong data-start=\"3775\" data-end=\"3823\">\u00a1Cuidando el planeta, orgullosamente Newport!<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be38429 elementor-widget elementor-widget-image\" data-id=\"be38429\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News.webp?w=1536\" title=\"Instalacion_Paneles_Solares_NPS_News\" alt=\"Instalacion_Paneles_Solares_NPS_News\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c60791 e-flex e-con-boxed e-con e-parent\" data-id=\"9c60791\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed124b2 elementor-widget elementor-widget-heading\" data-id=\"ed124b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Preguntas Frecuentes sobre el Proyecto Solar de Newport School<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-327f1b9 ha-has-bg-overlay elementor-widget elementor-widget-toggle\" data-id=\"327f1b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5291\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5291\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfCu\u00e1nta energ\u00eda generan los paneles solares de Newport School?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5291\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5291\"><p data-start=\"3862\" data-end=\"4109\">El sistema tiene una capacidad instalada de 80 kWp, distribuida en 244 paneles solares, y est\u00e1 proyectado para cubrir aproximadamente el 37% de la demanda energ\u00e9tica del colegio.<\/p><p data-start=\"4111\" data-end=\"4281\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5292\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5292\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 beneficios tiene la energ\u00eda solar en los colegios?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5292\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5292\"><p data-start=\"4283\" data-end=\"4519\">Reduce la huella ambiental, promueve el uso de energ\u00edas renovables, fortalece la educaci\u00f3n en sostenibilidad y disminuye la dependencia de fuentes energ\u00e9ticas convencionales.<\/p><p data-start=\"4521\" data-end=\"4721\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5293\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-5293\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfQu\u00e9 es un sistema solar fotovoltaico?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5293\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-5293\"><p data-start=\"4521\" data-end=\"4721\">Es una tecnolog\u00eda que convierte la luz solar en electricidad mediante paneles solares, permitiendo generar energ\u00eda limpia y renovable para diferentes usos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5294\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-5294\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm144 276c0 6.6-5.4 12-12 12h-92v92c0 6.6-5.4 12-12 12h-56c-6.6 0-12-5.4-12-12v-92h-92c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h92v-92c0-6.6 5.4-12 12-12h56c6.6 0 12 5.4 12 12v92h92c6.6 0 12 5.4 12 12v56z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-minus-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zM124 296c-6.6 0-12-5.4-12-12v-56c0-6.6 5.4-12 12-12h264c6.6 0 12 5.4 12 12v56c0 6.6-5.4 12-12 12H124z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfPor qu\u00e9 Newport School instal\u00f3 paneles solares?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-5294\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-5294\"><div class=\"qMYqUG_convSearchResultHighlightRoot\"><div class=\"\" data-turn-id-container=\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\" data-is-intersecting=\"true\"><section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\" data-turn-id-container=\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\" data-testid=\"conversation-turn-2\" data-turn=\"assistant\"><div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\"><div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\"><div class=\"flex max-w-full flex-col gap-4 grow\"><div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"132e11e6-9448-4dd2-a8ea-a8c9259fe205\" data-message-model-slug=\"gpt-5-5\" data-turn-start-message=\"true\"><div class=\"flex w-full flex-col gap-1 empty:hidden\"><div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\"><p data-start=\"4723\" data-end=\"4971\" data-is-last-node=\"\" data-is-only-node=\"\">Como parte de su compromiso con la sostenibilidad, la innovaci\u00f3n y la formaci\u00f3n de estudiantes que comprendan la importancia del cuidado del medio ambiente y el uso responsable de los recursos.<\/p><\/div><\/div><\/div><\/div><div class=\"z-0 flex min-h-[46px] justify-start\">\u00a0<\/div><div class=\"mt-3 w-full empty:hidden\"><div class=\"text-center\">\u00a0<\/div><\/div><\/div><\/div><\/section><\/div><\/div><div class=\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\" aria-hidden=\"true\">\u00a0<\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"\\u00bfCu\\u00e1nta energ\\u00eda generan los paneles solares de Newport School?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p data-start=\\\"3862\\\" data-end=\\\"4109\\\">El sistema tiene una capacidad instalada de 80 kWp, distribuida en 244 paneles solares, y est\\u00e1 proyectado para cubrir aproximadamente el 37% de la demanda energ\\u00e9tica del colegio.<\\\/p><p data-start=\\\"4111\\\" data-end=\\\"4281\\\">\\u00a0<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfQu\\u00e9 beneficios tiene la energ\\u00eda solar en los colegios?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p data-start=\\\"4283\\\" data-end=\\\"4519\\\">Reduce la huella ambiental, promueve el uso de energ\\u00edas renovables, fortalece la educaci\\u00f3n en sostenibilidad y disminuye la dependencia de fuentes energ\\u00e9ticas convencionales.<\\\/p><p data-start=\\\"4521\\\" data-end=\\\"4721\\\">\\u00a0<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfQu\\u00e9 es un sistema solar fotovoltaico?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p data-start=\\\"4521\\\" data-end=\\\"4721\\\">Es una tecnolog\\u00eda que convierte la luz solar en electricidad mediante paneles solares, permitiendo generar energ\\u00eda limpia y renovable para diferentes usos.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"\\u00bfPor qu\\u00e9 Newport School instal\\u00f3 paneles solares?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<div class=\\\"qMYqUG_convSearchResultHighlightRoot\\\"><div class=\\\"\\\" data-turn-id-container=\\\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\\\" data-is-intersecting=\\\"true\\\"><section class=\\\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\\\" dir=\\\"auto\\\" data-turn-id=\\\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\\\" data-turn-id-container=\\\"request-WEB:1e7661af-c1bf-4c61-8921-831b67b63d77-0\\\" data-testid=\\\"conversation-turn-2\\\" data-turn=\\\"assistant\\\"><div class=\\\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\\\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\\\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\\\"><div class=\\\"[--thread-content-max-width:40rem] @w-lg\\\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\\\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\\\" data-conversation-screenshot-content=\\\"\\\"><div class=\\\"flex max-w-full flex-col gap-4 grow\\\"><div class=\\\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\\\" dir=\\\"auto\\\" data-message-author-role=\\\"assistant\\\" data-message-id=\\\"132e11e6-9448-4dd2-a8ea-a8c9259fe205\\\" data-message-model-slug=\\\"gpt-5-5\\\" data-turn-start-message=\\\"true\\\"><div class=\\\"flex w-full flex-col gap-1 empty:hidden\\\"><div class=\\\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\\\"><p data-start=\\\"4723\\\" data-end=\\\"4971\\\" data-is-last-node=\\\"\\\" data-is-only-node=\\\"\\\">Como parte de su compromiso con la sostenibilidad, la innovaci\\u00f3n y la formaci\\u00f3n de estudiantes que comprendan la importancia del cuidado del medio ambiente y el uso responsable de los recursos.<\\\/p><\\\/div><\\\/div><\\\/div><\\\/div><div class=\\\"z-0 flex min-h-[46px] justify-start\\\">\\u00a0<\\\/div><div class=\\\"mt-3 w-full empty:hidden\\\"><div class=\\\"text-center\\\">\\u00a0<\\\/div><\\\/div><\\\/div><\\\/div><\\\/section><\\\/div><\\\/div><div class=\\\"pointer-events-none -mt-px h-px translate-y-[calc(var(--scroll-root-safe-area-inset-bottom)-14*var(--spacing))]\\\" aria-hidden=\\\"true\\\">\\u00a0<\\\/div>\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Newport School la educaci\u00f3n del futuro se vive en nuestra infraestructura. Con gran orgullo compartimos con toda nuestra comunidad educativa una noticia hist\u00f3rica: hemos puesto en marcha nuestro propio [&hellip;]<\/p>\n","protected":false},"featured_media":134472,"template":"","class_list":["post-134466","school-news","type-school-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/newportschool\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/\",\"name\":\"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Instalacion_Paneles_Solares_NPS_News2.webp\",\"datePublished\":\"2026-06-17T19:38:30+00:00\",\"description\":\"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Instalacion_Paneles_Solares_NPS_News2.webp\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Instalacion_Paneles_Solares_NPS_News2.webp\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"description\":\"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!\",\"publisher\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"width\":808,\"height\":388,\"caption\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/newportschool\\\/\",\"https:\\\/\\\/instagram.com\\\/newportschool\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkuOH6cSzNNej7FE8wZ4bMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/","og_locale":"es_ES","og_type":"article","og_title":"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","og_description":"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.","og_url":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/","og_site_name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/newportschool\/","og_image":[{"width":2048,"height":1152,"url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/","url":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/","name":"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","isPartOf":{"@id":"https:\/\/newportschool.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News2.webp","datePublished":"2026-06-17T19:38:30+00:00","description":"Newport School da un gran paso hacia un futuro sostenible con su nueva planta de energ\u00eda solar, beneficiando a toda la comunidad educativa.","breadcrumb":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/#primaryimage","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News2.webp","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/06\/Instalacion_Paneles_Solares_NPS_News2.webp","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/newport-school-se-transforma-inauguramos-nuestro-sistema-de-paneles-solares-para-un-futuro-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newportschool.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"Newport School se transforma: Inauguramos nuestro sistema de paneles solares para un futuro sostenible"}]},{"@type":"WebSite","@id":"https:\/\/newportschool.edu.co\/es\/#website","url":"https:\/\/newportschool.edu.co\/es\/","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!","publisher":{"@id":"https:\/\/newportschool.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newportschool.edu.co\/es\/#organization","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","url":"https:\/\/newportschool.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","width":808,"height":388,"caption":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/newportschool\/","https:\/\/instagram.com\/newportschool\/","https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/134466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news"}],"about":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/types\/school-news"}],"version-history":[{"count":4,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/134466\/revisions"}],"predecessor-version":[{"id":134479,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/134466\/revisions\/134479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media\/134472"}],"wp:attachment":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media?parent=134466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}