{"id":135963,"date":"2026-08-28T08:36:46","date_gmt":"2026-08-28T13:36:46","guid":{"rendered":"https:\/\/newportschool.edu.co\/?post_type=school-news&#038;p=135963"},"modified":"2026-08-28T08:43:42","modified_gmt":"2026-08-28T13:43:42","slug":"dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones","status":"publish","type":"school-news","link":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/","title":{"rendered":"D\u00eda de los Abuelos: celebramos el amor que une generaciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"135963\" class=\"elementor elementor-135963\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\" data-elementor-post-type=\"school-news\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cc86da e-flex e-con-boxed e-con e-parent\" data-id=\"3cc86da\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a7957d6 elementor-widget elementor-widget-text-editor\" data-id=\"a7957d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\">En Newport School vivimos una jornada llena de cari\u00f1o, sonrisas y momentos que quedar\u00e1n en la memoria de nuestra comunidad. Celebramos el <strong>D\u00eda de los Abuelos<\/strong>, una ocasi\u00f3n especial para reconocer a quienes ocupan un lugar \u00fanico en la vida de nuestros estudiantes y compartir junto a ellos experiencias que fortalecen los v\u00ednculos familiares.<\/p><p>Durante este encuentro, nuestros abuelos tuvieron la oportunidad de disfrutar diferentes momentos junto a sus nietos, acompa\u00f1\u00e1ndolos en una celebraci\u00f3n pensada para compartir, agradecer y crear nuevos recuerdos.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f544ed2 e-flex e-con-boxed e-con e-parent\" data-id=\"f544ed2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c85975 elementor-widget elementor-widget-heading\" data-id=\"4c85975\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Un d\u00eda para compartir juntos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b9f87a e-flex e-con-boxed e-con e-parent\" data-id=\"7b9f87a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d85c15 elementor-widget elementor-widget-text-editor\" data-id=\"8d85c15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\">La jornada estuvo llena de experiencias especiales en las que nuestros estudiantes fueron protagonistas y tuvieron la oportunidad de demostrarles a sus abuelos cu\u00e1nto significan para ellos.<\/p><p class=\"isSelectedEnd\">Entre abrazos, sonrisas y momentos compartidos, las familias disfrutaron de un espacio para detenerse, celebrar el presente y fortalecer esos v\u00ednculos que se construyen a trav\u00e9s del tiempo.<\/p><p>Uno de los momentos m\u00e1s especiales se vivi\u00f3 en <strong>Preescolar<\/strong>, donde nuestros peque\u00f1os compartieron un divertido <strong>Fashion Show junto a sus abuelos<\/strong>. Ni\u00f1os y abuelos desfilaron juntos, disfrutando de una experiencia llena de creatividad, complicidad y mucha alegr\u00eda.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b3e74b e-flex e-con-boxed e-con e-parent\" data-id=\"9b3e74b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0ec748f elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"0ec748f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg?w=640\" alt=\"c48b1e6f-63b1-418b-ba9f-09d9c45c8918\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/CC434B51-0E7B-4568-B357-6282C1170EA9.jpg?w=640\" alt=\"CC434B51-0E7B-4568-B357-6282C1170EA9\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/db1a58e6-8680-4c8e-b404-8b0762c9e5be.jpg?w=640\" alt=\"db1a58e6-8680-4c8e-b404-8b0762c9e5be\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/8E5F9A6A-FB15-4F64-994B-946F1553A564.jpg?w=640\" alt=\"8E5F9A6A-FB15-4F64-994B-946F1553A564\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/73aafc7f-5a0a-44ce-8b4a-1db8fff40ebb.jpg?w=640\" alt=\"73aafc7f-5a0a-44ce-8b4a-1db8fff40ebb\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/0957A0D8-F229-4396-8F50-A20F8777F3F0.jpg?w=640\" alt=\"0957A0D8-F229-4396-8F50-A20F8777F3F0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/3404c381-ddc4-48f2-828d-81da1d0e4ff0.jpg?w=640\" alt=\"3404c381-ddc4-48f2-828d-81da1d0e4ff0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/07987925-7455-440A-9849-D59522CF28EC.jpg?w=640\" alt=\"07987925-7455-440A-9849-D59522CF28EC\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d01cfe e-flex e-con-boxed e-con e-parent\" data-id=\"0d01cfe\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d1d55 elementor-widget elementor-widget-heading\" data-id=\"c2d1d55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Detalles que nacen del coraz\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96d78b2 e-flex e-con-boxed e-con e-parent\" data-id=\"96d78b2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e63645 elementor-widget elementor-widget-text-editor\" data-id=\"5e63645\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\">Como parte de la celebraci\u00f3n, nuestros estudiantes prepararon detalles especiales para entregar a sus abuelos. Cada uno fue una muestra de cari\u00f1o y gratitud por el amor, las historias, los consejos y los momentos que comparten con ellos.<\/p><p>Porque muchas veces son los peque\u00f1os gestos los que se convierten en los recuerdos m\u00e1s grandes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3603918 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"3603918\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_9418.jpg?w=640\" alt=\"IMG_9418\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_9423.jpg?w=640\" alt=\"IMG_9423\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_9494.jpg?w=640\" alt=\"IMG_9494\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_9410.jpg?w=640\" alt=\"IMG_9410\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_4739.jpg?w=640\" alt=\"IMG_4739\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_4521.jpg?w=640\" alt=\"IMG_4521\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_4540.jpg?w=640\" alt=\"IMG_4540\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_4708.jpg?w=640\" alt=\"IMG_4708\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72a9ddd e-flex e-con-boxed e-con e-parent\" data-id=\"72a9ddd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-192736a elementor-widget elementor-widget-heading\" data-id=\"192736a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Celebrar los v\u00ednculos que nos hacen comunidad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f37910 e-flex e-con-boxed e-con e-parent\" data-id=\"5f37910\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b6162cd elementor-widget elementor-widget-text-editor\" data-id=\"b6162cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"isSelectedEnd\">El D\u00eda de los Abuelos nos record\u00f3 la importancia de crear espacios en los que las familias puedan encontrarse, compartir y ser parte de las experiencias que hacen parte de la vida escolar.<\/p><p class=\"isSelectedEnd\">En Newport School creemos que educar tambi\u00e9n significa construir comunidad y reconocer el valor de las relaciones que acompa\u00f1an a nuestros estudiantes mientras crecen.<\/p><p>Celebrar a nuestros abuelos fue, sobre todo, celebrar el amor que trasciende generaciones y que hace de cada momento compartido un recuerdo para guardar en el coraz\u00f3n.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956b872 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"956b872\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_0859.jpg?w=1536\" alt=\"IMG_0859\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_08491.jpg?w=1536\" alt=\"IMG_0849(1)\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/IMG_0854.jpg?w=1536\" alt=\"IMG_0854\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-16f7125 e-flex e-con-boxed e-con e-parent\" data-id=\"16f7125\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-89e2d2c e-con-full e-flex e-con e-child\" data-id=\"89e2d2c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53a8046 elementor-widget elementor-widget-heading\" data-id=\"53a8046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descubre una educaci\u00f3n diferente en Newport School\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47cbf4f elementor-widget elementor-widget-text-editor\" data-id=\"47cbf4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Si sue\u00f1as con que tu hij(a) crezca en un colegio donde el aprendizaje, el ingl\u00e9s, el arte y la formaci\u00f3n integral se viven con experiencias que dejan huella, te invitamos a conocer Newport School: <span style=\"text-decoration: underline\"><a href=\"https:\/\/newportschool.edu.co\/es\/admisiones\/\"><strong data-start=\"1281\" data-end=\"1405\">visita nuestras sedes y descubre por qu\u00e9 tantas familias eligen construir su historia con nosotros.<\/strong>\u00a0<img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/17.0.2\/svg\/1f49a.svg\" alt=\"\ud83d\udc9a\" \/><\/a><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ead15c e-con-full e-flex e-con e-child\" data-id=\"7ead15c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t<div data-ha-element-link=\"{&quot;url&quot;:&quot;https:\\\/\\\/newportschool.edu.co\\\/es\\\/curriculos-internacionales\\\/ruler\\\/&quot;,&quot;is_external&quot;:&quot;&quot;,&quot;nofollow&quot;:&quot;&quot;}\" style=\"cursor: pointer\" class=\"elementor-element elementor-element-e51408a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e51408a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/newportschool.edu.co\/es\/admisiones\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agenda un recorrido<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d35b60 elementor-widget elementor-widget-text-editor\" data-id=\"6d35b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400\">\ud83d\udccc <\/span><b>Agenda una visita<\/b><span style=\"font-weight: 400\"> y descubre por qu\u00e9 Newport School es la evoluci\u00f3n de la educaci\u00f3n <\/span><a href=\"https:\/\/newportschool.edu.co\/es\/curriculos-internacionales\/ruler\/\"><span style=\"font-weight: 400\"><span style=\"color: #69bd04\"><b><u>aqu\u00ed.<\/u><\/b><\/span><\/span><\/a><\/p><p><span style=\"font-weight: 400\">\ud83d\udccc <span style=\"text-decoration: underline\"><a href=\"https:\/\/newportschool.edu.co\/es\/blog\/recomendaciones-para-el-regreso-a-clases-de-tus-hijos\/\">Recomendaciones para el regreso a clases de tus hijos<br \/><\/a><\/span><\/span><\/p><p><span style=\"font-weight: 400\">\ud83d\udccc<span style=\"text-decoration: underline\"><a href=\"https:\/\/newportschool.edu.co\/es\/school-news\/asi-fue-nuestra-project-fair-proyectos-que-conectan-conocimiento-creatividad-y-proposito\/\">As\u00ed fue nuestra Project Fair: proyectos que conectan conocimiento, creatividad y prop\u00f3sito<\/a><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En Newport School vivimos una jornada llena de cari\u00f1o, sonrisas y momentos que quedar\u00e1n en la memoria de nuestra comunidad. Celebramos el D\u00eda de los Abuelos, una ocasi\u00f3n especial para [&hellip;]<\/p>\n","protected":false},"featured_media":135970,"template":"","class_list":["post-135963","school-news","type-school-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/newportschool\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T13:43:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/\",\"name\":\"D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/08\\\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg\",\"datePublished\":\"2026-08-28T13:36:46+00:00\",\"dateModified\":\"2026-08-28T13:43:42+00:00\",\"description\":\"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/08\\\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/08\\\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/school-news\\\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda de los Abuelos: celebramos el amor que une generaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"description\":\"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!\",\"publisher\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#organization\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"contentUrl\":\"https:\\\/\\\/newportschool.edu.co\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2024\\\/11\\\/cropped-LogoNewport-2.png\",\"width\":808,\"height\":388,\"caption\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/newportschool.edu.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/newportschool\\\/\",\"https:\\\/\\\/instagram.com\\\/newportschool\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkuOH6cSzNNej7FE8wZ4bMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","og_description":"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.","og_url":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/","og_site_name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/newportschool\/","article_modified_time":"2026-08-28T13:43:42+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/","url":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/","name":"D\u00eda de los Abuelos: celebramos el amor que une generaciones - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","isPartOf":{"@id":"https:\/\/newportschool.edu.co\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/#primaryimage"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg","datePublished":"2026-08-28T13:36:46+00:00","dateModified":"2026-08-28T13:43:42+00:00","description":"Celebramos el D\u00eda de los Abuelos en Newport School con momentos especiales, actividades junto a sus nietos y un emotivo Fashion Show en Preescolar.","breadcrumb":{"@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/#primaryimage","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2026\/08\/c48b1e6f-63b1-418b-ba9f-09d9c45c8918.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/newportschool.edu.co\/es\/school-news\/dia-de-los-abuelos-celebramos-el-amor-que-une-generaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newportschool.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"D\u00eda de los Abuelos: celebramos el amor que une generaciones"}]},{"@type":"WebSite","@id":"https:\/\/newportschool.edu.co\/es\/#website","url":"https:\/\/newportschool.edu.co\/es\/","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!","publisher":{"@id":"https:\/\/newportschool.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newportschool.edu.co\/es\/#organization","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","url":"https:\/\/newportschool.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","width":808,"height":388,"caption":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/newportschool\/","https:\/\/instagram.com\/newportschool\/","https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/135963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news"}],"about":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/types\/school-news"}],"version-history":[{"count":7,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/135963\/revisions"}],"predecessor-version":[{"id":136013,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/school-news\/135963\/revisions\/136013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media\/135970"}],"wp:attachment":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media?parent=135963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}