{"id":130024,"date":"2025-02-10T20:05:35","date_gmt":"2025-02-11T01:05:35","guid":{"rendered":"https:\/\/newportschool.edu.co\/event\/wellbeing-week\/"},"modified":"2025-02-10T20:05:35","modified_gmt":"2025-02-11T01:05:35","slug":"wellbeing-week","status":"publish","type":"tribe_events","link":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/","title":{"rendered":"Wellbeing Week"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Semana de bienestar donde se realizan actividades en torno a la salud mental y se generan herramientas para promover y fomentar el bienestar de la comunidad NPS.<\/p>\n","protected":false},"author":14,"featured_media":0,"template":"","meta":{"_acf_changed":false,"content-type":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[74,41,75],"tribe_events_cat":[73],"class_list":["post-130024","tribe_events","type-tribe_events","status-publish","hentry","tag-bienestar","tag-estudiantes","tag-salud-mental","tribe_events_cat-semana-de-bienestar","cat_semana-de-bienestar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Semana de bienestar donde se realizan actividades en torno a la salud mental y se generan herramientas para promover y fomentar el bienestar de la comunidad NPS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/\" \/>\n<meta property=\"og:site_name\" content=\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/newportschool\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/\",\"url\":\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/\",\"name\":\"Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/newportschool.edu.co\/es\/#website\"},\"datePublished\":\"2025-02-11T01:05:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/newportschool.edu.co\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\/\/newportschool.edu.co\/es\/events\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wellbeing Week\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/newportschool.edu.co\/es\/#website\",\"url\":\"https:\/\/newportschool.edu.co\/es\/\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"description\":\"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!\",\"publisher\":{\"@id\":\"https:\/\/newportschool.edu.co\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/newportschool.edu.co\/es\/#organization\",\"name\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\",\"url\":\"https:\/\/newportschool.edu.co\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png\",\"contentUrl\":\"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png\",\"width\":808,\"height\":388,\"caption\":\"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n\"},\"image\":{\"@id\":\"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/newportschool\/\",\"https:\/\/instagram.com\/newportschool\/\",\"https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","og_description":"Semana de bienestar donde se realizan actividades en torno a la salud mental y se generan herramientas para promover y fomentar el bienestar de la comunidad NPS.","og_url":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/","og_site_name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/newportschool\/","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/","url":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/","name":"Wellbeing Week - Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","isPartOf":{"@id":"https:\/\/newportschool.edu.co\/es\/#website"},"datePublished":"2025-02-11T01:05:35+00:00","breadcrumb":{"@id":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/newportschool.edu.co\/es\/event\/wellbeing-week\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/newportschool.edu.co\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/newportschool.edu.co\/es\/events\/"},{"@type":"ListItem","position":3,"name":"Wellbeing Week"}]},{"@type":"WebSite","@id":"https:\/\/newportschool.edu.co\/es\/#website","url":"https:\/\/newportschool.edu.co\/es\/","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","description":"Somos un colegio biling\u00fce, calendario A, con una metodolog\u00eda innovadora para preescolar, primaria y bachillerato. \u00a1Ven y vive la experiencia Newport School!","publisher":{"@id":"https:\/\/newportschool.edu.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/newportschool.edu.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/newportschool.edu.co\/es\/#organization","name":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n","url":"https:\/\/newportschool.edu.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","contentUrl":"https:\/\/newportschool.edu.co\/wp-content\/uploads\/sites\/28\/2024\/11\/cropped-LogoNewport-2.png","width":808,"height":388,"caption":"Newport School | Colegios Redcol La evoluci\u00f3n de la educaci\u00f3n"},"image":{"@id":"https:\/\/newportschool.edu.co\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/newportschool\/","https:\/\/instagram.com\/newportschool\/","https:\/\/www.youtube.com\/channel\/UCkuOH6cSzNNej7FE8wZ4bMQ"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/tribe_events\/130024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/users\/14"}],"version-history":[{"count":0,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/tribe_events\/130024\/revisions"}],"wp:attachment":[{"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/media?parent=130024"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/tags?post=130024"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/newportschool.edu.co\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=130024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}